{"id":7090,"date":"2026-04-30T11:51:04","date_gmt":"2026-04-30T17:51:04","guid":{"rendered":"https:\/\/wakeupradio.mx\/?p=7090"},"modified":"2026-04-30T11:51:35","modified_gmt":"2026-04-30T17:51:35","slug":"gp-de-mexico-motor-para-la-economia-gonzalez-compean","status":"publish","type":"post","link":"https:\/\/wakeupradio.mx\/index.php\/2026\/04\/30\/gp-de-mexico-motor-para-la-economia-gonzalez-compean\/","title":{"rendered":"GP de M\u00e9xico, motor para la econom\u00eda: Gonz\u00e1lez Compe\u00e1n||DEPORTES"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/wakeupradio.mx\/wp-content\/uploads\/2026\/04\/image-26-1024x683.png\" alt=\"\" class=\"wp-image-7091\" srcset=\"https:\/\/wakeupradio.mx\/wp-content\/uploads\/2026\/04\/image-26-1024x683.png 1024w, https:\/\/wakeupradio.mx\/wp-content\/uploads\/2026\/04\/image-26-300x200.png 300w, https:\/\/wakeupradio.mx\/wp-content\/uploads\/2026\/04\/image-26-768x512.png 768w, https:\/\/wakeupradio.mx\/wp-content\/uploads\/2026\/04\/image-26.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-small-font-size\">Este a\u00f1o se prev\u00e9 que las ganancias aumenten con el regreso del mexicano Sergio P\u00e9rez.<\/p>\n\n\n\n<p>A pesar de la ausencia del piloto mexicano Sergio P\u00e9rez en la parrilla, el Gran Premio de la Ciudad de M\u00e9xico 2025 fue uno de los m\u00e1s exitosos en la historia de la carrera al generar una derrama de 19 mil 840 millones de pesos para el pa\u00eds, consolid\u00e1ndose como el evento deportivo anual m\u00e1s importante.<\/p>\n\n\n\n<p>Seg\u00fan an\u00e1lisis elaborados por las empresas internacionales AECOM y Formula Money, contratadas por CIE para medir el impacto y los beneficios de la carrera para el pa\u00eds, el certamen \u2013celebrado del pasado 24 al 26 de octubre de 2025\u2013 registr\u00f3 cifras millonarias.<\/p>\n\n\n\n<p>\u201cEl GP de M\u00e9xico se ha convertido en un motor para la econom\u00eda nacional, al generar empleos y posicionar a la Ciudad de M\u00e9xico como un destino tur\u00edstico de clase mundial. Estos n\u00fameros demuestran que nuestra fiesta es un gran referente de la industria, respaldado por una extraordinaria afici\u00f3n que asiste con gran entusiasmo al aut\u00f3dromo Hermanos Rodr\u00edguez\u201d, dijo Federico Gonz\u00e1lez Compe\u00e1n, director general de la carrera.<\/p>\n\n\n\n<p>De los 19 mil 840 millones de pesos, 6 mil 715 fueron en derra-ma directa y 13 mil 125 en exposici\u00f3n de medios para M\u00e9xico. Las operaciones de CIE para celebrar el GP de M\u00e9xico 2025 generaron 3 mil 705 millones de pesos.<\/p>\n\n\n\n<p>El Gran Premio origin\u00f3 10 mil 649 empleos en la regi\u00f3n, con una derrama de mil 130 millones de pesos. CIE cre\u00f3 5 mil 170, generando m\u00e1s de 770 millones de pesos en salarios. Los gastos&nbsp;<em>ex situ&nbsp;<\/em>de los miembros de las escuder\u00edas y turistas que acudieron al evento contabilizaron 3 mil 410 millones en actividad econ\u00f3mica adicional para la Ciudad de M\u00e9xico, sustentando 5 mil 600 empleos y 370 millones en salarios.<\/p>\n\n\n\n<p>El GP de M\u00e9xico 2025 registr\u00f3 una entrada de 401 mil 326 asistentes durante los tres d\u00edas. S\u00f3lo el domingo estuvieron presentes 153 mil 867 espectadores.<\/p>\n\n\n\n<p>Desde el 2015, la carrera ha dejado una derrama econ\u00f3mica y de exposici\u00f3n de medios de M\u00e9xico acumulada de 157 mil 594 millones de pesos. Adem\u00e1s, ha generado un total de 93 mil 175 empleos, equivalente a 12 mil 629 millones de pesos en salarios.<\/p>\n\n\n\n<p>Adem\u00e1s, del 25 al 27 de octubre de 2025 ingresaron al pa\u00eds 238 mil turistas, lo que represent\u00f3 un aumento de 2.8 por ciento comparado con el a\u00f1o anterior. La ocupaci\u00f3n hotelera alcanz\u00f3 un promedio de 79.2 por ciento, equivalente de 132 mil 667 habitaciones ocupadas para una ganancia de 2 mil 203 millones 587 mil pesos.<\/p>\n\n\n\n<p>La carrera mexicana est\u00e1 dentro de las tres m\u00e1s caras del calendario, s\u00f3lo por debajo de Las Vegas y Miami. Hace una d\u00e9cada, el boleto m\u00e1s barato para ver la F\u00f3rmula 1 costaba mil 500 pesos y el a\u00f1o pasado el de menor precio estuvo en 3 mil 900.<\/p>\n\n\n\n<p>El contrato de F\u00f3rmula 1 se ha alargado en nuestro pa\u00eds gracias a las millonarias ganancias y al&nbsp;<em>boom&nbsp;<\/em>entre los aficionados. En abril pasado, se firm\u00f3 una extensi\u00f3n contractual hasta 2028, lo cual abre la puerta para una nueva negociaci\u00f3n.<\/p>\n\n\n\n<p>Con la edici\u00f3n 2026 en puerta y el esperado regreso de Checo P\u00e9rez, ahora con Cadillac, el GP de M\u00e9xico se apuntala para seguir como un impulsor de la econom\u00eda nacional, adem\u00e1s de ser una de las principales plataformas para proyectar la cultura de pa\u00eds al mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o se prev\u00e9 que las ganancias aumenten con el regreso del mexicano Sergio P\u00e9rez. A pesar de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-7090","post","type-post","status-publish","format-standard","hentry","category-deportes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/posts\/7090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7090"}],"version-history":[{"count":2,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/posts\/7090\/revisions"}],"predecessor-version":[{"id":7093,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/posts\/7090\/revisions\/7093"}],"wp:attachment":[{"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wakeupradio.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}